{"id":1944,"date":"2010-02-22T21:44:13","date_gmt":"2010-02-22T20:44:13","guid":{"rendered":"http:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/?p=1944"},"modified":"2010-05-02T06:26:12","modified_gmt":"2010-05-02T05:26:12","slug":"baybaro-von-der-ora-maritima","status":"publish","type":"post","link":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/1944\/","title":{"rendered":"Baybaro von der Ora Maritima"},"content":{"rendered":"<h3><strong><span style=\"color: #993300;\"><a href=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?ssl=1\"><img data-attachment-id=\"1945\" data-permalink=\"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/1944\/brehmeebendorf_0007\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?fit=1150%2C768&amp;ssl=1\" data-orig-size=\"1150,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"BrehmeEbendorf_0007\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?fit=584%2C390&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" class=\"size-large wp-image-1945 alignleft\" title=\"BrehmeEbendorf_0007\" src=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?resize=230%2C153&#038;ssl=1\" alt=\"Baybaro von der Ora Maritima\" width=\"230\" height=\"153\" srcset=\"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2010\/02\/BrehmeEbendorf_0007.jpg?w=1150&amp;ssl=1 1150w\" sizes=\"(max-width: 230px) 100vw, 230px\" data-recalc-dims=\"1\" \/><\/a><\/span><\/strong><strong>Jiipiie!<\/strong> Und das ist der <strong><span style=\"color: #993300;\">Papa unserer A-chens. <span style=\"color: #0000ff;\">Baybaro <\/span><\/span><\/strong>holte sich am Wochenende auf der Gemeinschafts-Rassehunde-Austellung in <strong>Recklinghausen <\/strong>den <strong><span style=\"color: #993300;\">1.Platz in der offenen Klasse, war &#8220;Bester R&#252;de&#8221; und dazu noch &#8220;BOB&#8221;! <\/span><span style=\"color: #000000;\"><br \/>\n<\/span><\/strong><\/h3>\n<h3><strong><span style=\"color: #000000;\">Herzlichen Gl&#252;ckwunsch!<\/span><\/strong><strong><span style=\"color: #993300;\"><br \/>\n<\/span><\/strong><\/h3>\n<p style=\"text-align: center;\"><strong><span style=\"color: #993300;\"><br \/>\n<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jiipiie! Und das ist der Papa unserer A-chens. Baybaro holte sich am Wochenende auf der Gemeinschafts-Rassehunde-Austellung in Recklinghausen den 1.Platz in der offenen Klasse, war &#8220;Bester R&#252;de&#8221; und dazu noch &#8220;BOB&#8221;! Herzlichen Gl&#252;ckwunsch!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":[]},"categories":[3],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/px1eF-vm","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":934,"url":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/934\/","url_meta":{"origin":1944,"position":0},"title":"Pappe und Papa","date":"20. Juli 2009","format":false,"excerpt":"Gestern haben wir am vormittag einen Pappkarton zerlegt und am Nachmittag hatten wir Besuch von Baybaro von der Ora Maritima. Das ist unser Papa - oh, wie wir uns gefreut haben!!!","rel":"","context":"In &quot;A-Wurf&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2009\/07\/welpen-tag41_1138-383x256.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":798,"url":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/798\/","url_meta":{"origin":1944,"position":1},"title":"Ares","date":"7. Juli 2009","format":false,"excerpt":"Er ist der Kr\u00e4ftigste unter unseren Welpen. ARES ist urgem\u00fctlich, geduldig, souver\u00e4n und gar nicht so leicht aus der Ruhe zu bringen - ein wirklich knuffiger Kerl, der seinem Vater - Baybaro von der Ora Maritima - alle Ehre macht (die anderen nat\u00fcrlich auch).","rel":"","context":"In &quot;A-Wurf&quot;","img":{"alt_text":"ares-tag28_0460-seilkampf","src":"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2009\/07\/ares-tag28_0460-seilkampf-1024x683.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":988,"url":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/988\/","url_meta":{"origin":1944,"position":2},"title":"Perfekt!","date":"26. Juli 2009","format":false,"excerpt":"Dr.\u00a0 Kroeger - Tierarzt aus Berlin - f\u00fchrte heute die AEP- Untersuchung bei unseren A-chens durch. Ergebnis: Super, spitzenm\u00e4\u00dfig,\u00a0 ein fehlerfreier Wurf! Alle 8 Fleckenzwerge sind bilateral h\u00f6rend. Hier haben wir also mit der Verpaarung unserer Hummel vom Magdeburger Domfelsen mit Baybaro von der Ora Maritima voll ins Schwarze getroffen.\u2026","rel":"","context":"In &quot;A-Wurf&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-content\/uploads\/2009\/07\/welpen-tag-48-AEP_1813-383x256.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":57,"url":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/57\/","url_meta":{"origin":1944,"position":3},"title":"Wir erwarten s&#252;&#223;e Dalmatinerwelpen","date":"13. Mai 2009","format":false,"excerpt":"Wir erwarten am 08.06.09 aus exzellenter Verpaarung mindestens 4 Dalmatinerwelpen . Die Elterntiere sind kerngesund, erfolgreich und wundersch\u00f6n und haben eine tolle Ahnenreihe. Wir sind Mitglied im DVD und z\u00fcchten nach strengen Regeln wesensfeste, familienfreundliche und gesunde Dalmatiner mit Papieren und Ahnentafel,geimpft, entwurmt, gechipt und audiometrisch untersucht, sowie an Familie,\u2026","rel":"","context":"In &quot;Z\u00fcchterinfo&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/posts\/1944"}],"collection":[{"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/comments?post=1944"}],"version-history":[{"count":6,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/posts\/1944\/revisions"}],"predecessor-version":[{"id":1948,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/posts\/1944\/revisions\/1948"}],"wp:attachment":[{"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/media?parent=1944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/categories?post=1944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dalmatiner-sachsen-anhalt.de\/blog\/wp-json\/wp\/v2\/tags?post=1944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}